{"id":95433,"date":"2021-10-07T12:06:03","date_gmt":"2021-10-07T10:06:03","guid":{"rendered":"https:\/\/www.maurawasescha.com\/?post_type=portfolio&#038;p=95433"},"modified":"2026-01-05T17:42:56","modified_gmt":"2026-01-05T16:42:56","slug":"park-residence-pontresina-engadin-ch0877","status":"publish","type":"portfolio","link":"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/","title":{"rendered":"Roseg Glacier Panorama | Pontresina | Engadine | CH0877"},"content":{"rendered":"<div id='referenzen'  class='avia-section av-j0m984-414ed4637a3a987e5fdd35775d92ce57 main_color avia-section-default avia-no-border-styling  avia-builder-el-0  avia-builder-el-no-sibling  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-95433'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-houfn8-5dea5fd413ebe6e20eb3d319559155d7\">\n.flex_column.av-houfn8-5dea5fd413ebe6e20eb3d319559155d7{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-houfn8-5dea5fd413ebe6e20eb3d319559155d7 av_one_half  avia-builder-el-1  el_before_av_one_half  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k0w0u6a4-9c1a10089be6d59c108897520ec9424b\">\n#top .avia-gallery.av-k0w0u6a4-9c1a10089be6d59c108897520ec9424b .avia-gallery-thumb a{\nwidth:20%;\n}\n<\/style>\n<div  class='avia-gallery av-k0w0u6a4-9c1a10089be6d59c108897520ec9424b avia_animate_when_visible  avia-builder-el-2  avia-builder-el-no-sibling  deactivate_avia_lazyload av-slideshow-ui av-loop-manual-endless av-control-hidden av-navigate-arrows av-navigate-dots hover-effect av-control-hidden avia-gallery-animate avia-gallery-1'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><meta itemprop=\"contentURL\" content=\"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/\"><div class='avia-gallery-big-wrapper'><a class='avia-gallery-big fakeLightbox lightbox avia-gallery-big-crop-thumb ' href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032-300x259.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032-768x664.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032-705x609.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\"  data-onclick='1' title='Wasescha_APT9_21_032' ><span class='avia-gallery-big-inner'  itemprop=\"thumbnailUrl\" ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-97869 avia-img-lazy-loading-not-97869\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032-845x684.jpg\" title='Wasescha_APT9_21_032' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032-495x400.jpg 495w\" sizes=\"(max-width: 845px) 100vw, 845px\" \/><\/span><\/a><\/div><div class='avia-gallery-thumb'><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032-300x259.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032-768x664.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032-705x609.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032-845x684.jpg' class='first_thumb lightbox ' data-onclick='1' title='Wasescha_APT9_21_032'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-97869 avia-img-lazy-loading-not-97869\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_032' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-97869 avia-img-lazy-loading-97869\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032-845x684.jpg\" title='Wasescha_APT9_21_032' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_032-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031-300x208.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031-768x532.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031-939x650.jpg 939w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031-1018x705.jpg 1018w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031-705x488.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031-845x684.jpg' class='lightbox ' data-onclick='2' title='Wasescha_APT9_21_031'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-97866 avia-img-lazy-loading-not-97866\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_031' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-97866 avia-img-lazy-loading-97866\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031-845x684.jpg\" title='Wasescha_APT9_21_031' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_033.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_033.jpg 1023w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_033-300x218.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_033-768x557.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_033-705x511.jpg 705w\" data-sizes=\"(max-width: 1023px) 100vw, 1023px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_033-845x684.jpg' class='lightbox ' data-onclick='3' title='Wasescha_APT9_21_033'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-97872 avia-img-lazy-loading-not-97872\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_033-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_033' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_033-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_033-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_033-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-97872 avia-img-lazy-loading-97872\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_033-845x684.jpg\" title='Wasescha_APT9_21_033' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_033-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_033-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_034.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_034.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_034-300x214.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_034-768x548.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_034-260x185.jpg 260w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_034-705x503.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_034-845x684.jpg' class='lightbox ' data-onclick='4' title='Wasescha_APT9_21_034'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-97875 avia-img-lazy-loading-not-97875\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_034-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_034' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_034-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_034-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_034-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-97875 avia-img-lazy-loading-97875\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_034-845x684.jpg\" title='Wasescha_APT9_21_034' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_034-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_034-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_030.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_030.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_030-300x215.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_030-768x551.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_030-705x506.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_030-845x684.jpg' class='lightbox ' data-onclick='5' title='Wasescha_APT9_21_030'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-97863 avia-img-lazy-loading-not-97863\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_030-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_030' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_030-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_030-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_030-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-97863 avia-img-lazy-loading-97863\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_030-845x684.jpg\" title='Wasescha_APT9_21_030' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_030-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_030-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_035.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_035.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_035-300x221.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_035-768x567.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_035-705x520.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_035-845x684.jpg' class='first_thumb lightbox ' data-onclick='6' title='Wasescha_APT9_21_035'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-97878 avia-img-lazy-loading-not-97878\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_035-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_035' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_035-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_035-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_035-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-97878 avia-img-lazy-loading-97878\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_035-845x684.jpg\" title='Wasescha_APT9_21_035' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_035-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_035-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_011.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_011.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_011-300x225.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_011-768x576.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_011-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_011-845x684.jpg' class='lightbox ' data-onclick='7' title='Wasescha_APT9_21_011'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-95352 avia-img-lazy-loading-not-95352\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_011-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_011' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_011-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_011-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_011-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-95352 avia-img-lazy-loading-95352\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_011-845x684.jpg\" title='Wasescha_APT9_21_011' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_011-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_011-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_004.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_004.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_004-300x278.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_004-768x713.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_004-705x654.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_004-845x684.jpg' class='lightbox ' data-onclick='8' title='Wasescha_APT9_21_004'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-95331 avia-img-lazy-loading-not-95331\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_004-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_004' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_004-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_004-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_004-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-95331 avia-img-lazy-loading-95331\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_004-845x684.jpg\" title='Wasescha_APT9_21_004' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_004-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_004-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_027.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_027.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_027-225x300.jpg 225w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_027-529x705.jpg 529w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_027-768x684.jpg' class='lightbox ' data-onclick='9' title='Wasescha_APT9_21_027'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-95400 avia-img-lazy-loading-not-95400\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_027-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_027' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_027-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_027-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_027-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-95400 avia-img-lazy-loading-95400\"  width=\"768\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_027-768x684.jpg\" title='Wasescha_APT9_21_027' alt='' \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_036.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_036.jpg 774w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_036-227x300.jpg 227w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_036-768x1016.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_036-533x705.jpg 533w\" data-sizes=\"(max-width: 774px) 100vw, 774px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_036-774x684.jpg' class='lightbox ' data-onclick='10' title='Wasescha_APT9_21_036'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-97881 avia-img-lazy-loading-not-97881\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_036-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_036' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_036-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_036-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_036-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-97881 avia-img-lazy-loading-97881\"  width=\"774\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_036-774x684.jpg\" title='Wasescha_APT9_21_036' alt='' \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_010.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_010.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_010-300x225.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_010-768x576.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_010-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_010-845x684.jpg' class='first_thumb lightbox ' data-onclick='11' title='Wasescha_APT9_21_010'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-95349 avia-img-lazy-loading-not-95349\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_010-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_010' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_010-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_010-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_010-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-95349 avia-img-lazy-loading-95349\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_010-845x684.jpg\" title='Wasescha_APT9_21_010' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_010-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_010-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_008.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_008.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_008-300x225.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_008-768x576.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_008-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_008-845x684.jpg' class='lightbox ' data-onclick='12' title='Wasescha_APT9_21_008'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-95343 avia-img-lazy-loading-not-95343\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_008-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_008' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_008-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_008-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_008-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-95343 avia-img-lazy-loading-95343\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_008-845x684.jpg\" title='Wasescha_APT9_21_008' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_008-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_008-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_009.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_009.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_009-300x225.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_009-768x576.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_009-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_009-845x684.jpg' class='lightbox ' data-onclick='13' title='Wasescha_APT9_21_009'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-95346 avia-img-lazy-loading-not-95346\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_009-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_009' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_009-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_009-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_009-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-95346 avia-img-lazy-loading-95346\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_009-845x684.jpg\" title='Wasescha_APT9_21_009' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_009-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_009-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_013.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_013.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_013-225x300.jpg 225w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_013-529x705.jpg 529w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_013-768x684.jpg' class='lightbox ' data-onclick='14' title='Wasescha_APT9_21_013'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-95358 avia-img-lazy-loading-not-95358\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_013-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_013' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_013-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_013-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_013-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-95358 avia-img-lazy-loading-95358\"  width=\"768\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_013-768x684.jpg\" title='Wasescha_APT9_21_013' alt='' \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_014.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_014.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_014-300x225.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_014-768x576.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_014-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_014-845x684.jpg' class='lightbox ' data-onclick='15' title='Wasescha_APT9_21_014'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-95361 avia-img-lazy-loading-not-95361\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_014-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_014' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_014-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_014-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_014-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-95361 avia-img-lazy-loading-95361\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_014-845x684.jpg\" title='Wasescha_APT9_21_014' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_014-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_014-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_015.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_015.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_015-300x230.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_015-768x590.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_015-705x541.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_015-845x684.jpg' class='first_thumb lightbox ' data-onclick='16' title='Wasescha_APT9_21_015'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-95364 avia-img-lazy-loading-not-95364\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_015-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_015' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_015-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_015-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_015-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-95364 avia-img-lazy-loading-95364\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_015-845x684.jpg\" title='Wasescha_APT9_21_015' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_015-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_015-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_018.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_018.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_018-300x225.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_018-768x576.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_018-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_018-845x684.jpg' class='lightbox ' data-onclick='17' title='Wasescha_APT9_21_018'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-95373 avia-img-lazy-loading-not-95373\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_018-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_018' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_018-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_018-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_018-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-95373 avia-img-lazy-loading-95373\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_018-845x684.jpg\" title='Wasescha_APT9_21_018' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_018-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_018-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_020.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_020.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_020-300x225.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_020-768x576.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_020-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_020-845x684.jpg' class='lightbox ' data-onclick='18' title='Wasescha_APT9_21_020'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-95379 avia-img-lazy-loading-not-95379\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_020-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_020' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_020-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_020-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_020-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-95379 avia-img-lazy-loading-95379\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_020-845x684.jpg\" title='Wasescha_APT9_21_020' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_020-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_020-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_028.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_028.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_028-300x225.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_028-768x576.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_028-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_028-845x684.jpg' class='lightbox ' data-onclick='19' title='Wasescha_APT9_21_028'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-95403 avia-img-lazy-loading-not-95403\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_028-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_028' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_028-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_028-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_028-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-95403 avia-img-lazy-loading-95403\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_028-845x684.jpg\" title='Wasescha_APT9_21_028' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_028-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_028-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_016.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_016.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_016-300x225.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_016-768x576.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_016-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_016-845x684.jpg' class='lightbox ' data-onclick='20' title='Wasescha_APT9_21_016'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-95367 avia-img-lazy-loading-not-95367\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_016-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_016' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_016-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_016-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_016-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-95367 avia-img-lazy-loading-95367\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_016-845x684.jpg\" title='Wasescha_APT9_21_016' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_016-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_016-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_017.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_017.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_017-300x225.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_017-768x576.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_017-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_017-845x684.jpg' class='first_thumb lightbox ' data-onclick='21' title='Wasescha_APT9_21_017'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-95370 avia-img-lazy-loading-not-95370\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_017-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_017' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_017-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_017-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_017-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-95370 avia-img-lazy-loading-95370\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_017-845x684.jpg\" title='Wasescha_APT9_21_017' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_017-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_017-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_022.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_022.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_022-300x225.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_022-768x576.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_022-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_022-845x684.jpg' class='lightbox ' data-onclick='22' title='Wasescha_APT9_21_022'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-95385 avia-img-lazy-loading-not-95385\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_022-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_022' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_022-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_022-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_022-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-95385 avia-img-lazy-loading-95385\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_022-845x684.jpg\" title='Wasescha_APT9_21_022' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_022-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_022-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_026.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_026.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_026-300x225.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_026-768x576.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_026-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_026-845x684.jpg' class='lightbox ' data-onclick='23' title='Wasescha_APT9_21_026'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-95397 avia-img-lazy-loading-not-95397\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_026-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_026' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_026-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_026-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_026-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-95397 avia-img-lazy-loading-95397\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_026-845x684.jpg\" title='Wasescha_APT9_21_026' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_026-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_026-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_023.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_023.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_023-300x225.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_023-768x576.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_023-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_023-845x684.jpg' class='lightbox ' data-onclick='24' title='Wasescha_APT9_21_023'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-95388 avia-img-lazy-loading-not-95388\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_023-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_023' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_023-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_023-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_023-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-95388 avia-img-lazy-loading-95388\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_023-845x684.jpg\" title='Wasescha_APT9_21_023' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_023-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_023-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_024.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_024.jpg 1024w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_024-300x225.jpg 300w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_024-768x576.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_024-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_024-845x684.jpg' class='lightbox ' data-onclick='25' title='Wasescha_APT9_21_024'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-95391 avia-img-lazy-loading-not-95391\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_024-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_024' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_024-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_024-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_024-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-95391 avia-img-lazy-loading-95391\"  width=\"845\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_024-845x684.jpg\" title='Wasescha_APT9_21_024' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_024-845x684.jpg 845w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_024-495x400.jpg 495w\" sizes=\"auto, (max-width: 845px) 100vw, 845px\" \/><\/div><\/a><a href=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_025.jpg\" data-srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_025.jpg 768w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_025-225x300.jpg 225w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_025-529x705.jpg 529w\" data-sizes=\"(max-width: 768px) 100vw, 768px\" data-rel='gallery-1' data-prev-img='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_025-768x684.jpg' class='first_thumb lightbox ' data-onclick='26' title='Wasescha_APT9_21_025'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-95394 avia-img-lazy-loading-not-95394\"   src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_025-180x180.jpg\" width=\"180\" height=\"180\"  title='Wasescha_APT9_21_025' alt='' srcset=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_025-180x180.jpg 180w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_025-80x80.jpg 80w, https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_025-36x36.jpg 36w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-95394 avia-img-lazy-loading-95394\"  width=\"768\" height=\"684\" src=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/10\/Wasescha_APT9_21_025-768x684.jpg\" title='Wasescha_APT9_21_025' alt='' \/><\/div><\/a><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ftrix0-8a319d95268fc2b4cce5230895cd237a\">\n.flex_column.av-ftrix0-8a319d95268fc2b4cce5230895cd237a{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-ftrix0-8a319d95268fc2b4cce5230895cd237a av_one_half  avia-builder-el-3  el_after_av_one_half  el_before_av_one_half  flex_column_div av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-42u9g8-f786d14ad1dc7c18fdc73fd33143dd95\">\n#top .av-special-heading.av-42u9g8-f786d14ad1dc7c18fdc73fd33143dd95{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-42u9g8-f786d14ad1dc7c18fdc73fd33143dd95 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-42u9g8-f786d14ad1dc7c18fdc73fd33143dd95 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-42u9g8-f786d14ad1dc7c18fdc73fd33143dd95 av-special-heading-h1 blockquote modern-quote  avia-builder-el-4  el_before_av_textblock  avia-builder-el-first '><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >Roseg Glacier Panorama | Pontresina | CH0877<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-b0qqwo-2e017dcbdb7ba77a1fe752e7e1e389d6 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Pontresina | Engadine | Switzerland | CH0877<\/p>\n<p>Dream apartment with a magnificent view of the Engadine mountains<\/p>\n<p><strong>Facts &amp; Figures:<\/strong><\/p>\n<p>Large living room<\/p>\n<p>Large dining room with beautiful mountain view<\/p>\n<p>Large kitchen<\/p>\n<p>3 bedrooms with bathroom<\/p>\n<p>1 Guest bathroom<\/p>\n<p>2 Parking spaces in the garage<\/p>\n<\/div><\/section><br \/>\n<section  class='av_textblock_section av-7uw8m0-c234ff48e109b4251d920fdb58b6288e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5jioyc-c6ef4e65c1a67d1d29bce1be39d77ac5\">\n.flex_column.av-5jioyc-c6ef4e65c1a67d1d29bce1be39d77ac5{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-5jioyc-c6ef4e65c1a67d1d29bce1be39d77ac5 av_one_half  avia-builder-el-7  el_after_av_one_half  el_before_av_one_half  first flex_column_div av-zero-column-padding  column-top-margin'     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5jioyc-aedec02d16492f0e3642870d7960f67c\">\n.flex_column.av-5jioyc-aedec02d16492f0e3642870d7960f67c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-5jioyc-aedec02d16492f0e3642870d7960f67c av_one_half  avia-builder-el-8  el_after_av_one_half  el_before_av_one_half  flex_column_div av-zero-column-padding  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2w472w-540791e90b6cc3ed6f6d9c0b2da33e8b\">\n#top .av-special-heading.av-2w472w-540791e90b6cc3ed6f6d9c0b2da33e8b{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-2w472w-540791e90b6cc3ed6f6d9c0b2da33e8b .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-2w472w-540791e90b6cc3ed6f6d9c0b2da33e8b .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-2w472w-540791e90b6cc3ed6f6d9c0b2da33e8b av-special-heading-h3 blockquote modern-quote  avia-builder-el-9  avia-builder-el-no-sibling '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Object documentation CH0877<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5jioyc-c6ef4e65c1a67d1d29bce1be39d77ac5\">\n.flex_column.av-5jioyc-c6ef4e65c1a67d1d29bce1be39d77ac5{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-5jioyc-c6ef4e65c1a67d1d29bce1be39d77ac5 av_one_half  avia-builder-el-10  el_after_av_one_half  el_before_av_one_third  first flex_column_div av-zero-column-padding  column-top-margin'     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4db25w-fd4d9c26b1507e6ccfb2e8f5690a9054\">\n.flex_column.av-4db25w-fd4d9c26b1507e6ccfb2e8f5690a9054{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-4db25w-fd4d9c26b1507e6ccfb2e8f5690a9054 av_one_third  avia-builder-el-11  el_after_av_one_half  avia-builder-el-last  flex_column_div av-zero-column-padding  column-top-margin'     ><div class='verkaufsdoku-container  av-styling-   avia-builder-el-12  avia-builder-el-no-sibling  avia-align-center'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\"  ><div class='avia-image-container-inner'><img class='avia_image ' src='https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2024\/06\/CH0877-Copertina-300x212.jpg' alt='' title='CH0877 Copertina'   itemprop=\"thumbnailUrl\"  \/><\/div><div class=\"form-style\" id=\"contact_form\">\n\t\t\t\t\t\t\t\t\t\t<div id=\"contact_body\">\n\t\t\t\t\t\t\t\t\t\t\t<br>Please enter your contact details in the form below. The entered data will be stored by us for a possible initiation of contact.<br><br>\n\t\t\t\t\t\t\t\t\t\t\t<input type=\"text\" name=\"subject\" id=\"subject\" class=\"input-field hidden\" value=\"Dokumentation Objekt CH0877*\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<input type=\"text\" name=\"name\" id=\"name\" required=\"true\" class=\"input-field\" placeholder=\"First name*\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<input type=\"text\" name=\"nachname\" id=\"nachname\" required=\"true\" class=\"input-field\" placeholder=\"Surname*\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<input type=\"text\" name=\"adresse\" id=\"adresse\" required=\"true\" class=\"input-field\" placeholder=\"Adress*\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<input type=\"text\" name=\"ort\" id=\"ort\" required=\"true\" class=\"input-field\" placeholder=\"City*\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<input type=\"text\" name=\"land\" id=\"land\" required=\"true\" class=\"input-field\" placeholder=\"Country*\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<input type=\"email\" name=\"email\" id=\"email\" required=\"true\" class=\"input-field\" placeholder=\"Email*\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<input type=\"tel\" name=\"phone_number\" required=\"true\" id=\"phone_number\"  class=\"tel-number-field\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<span id=\"valid-msg\" class=\"hide\">\u2713 Valid<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<span id=\"error-msg\" class=\"hide\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<script src=\"\/wp-content\/themes\/enfold-child\/components\/js\/intlTelInput.js\"><\/script>\n\t\t\t\t\t\t\t\t\t\t\t<script src=\"\/wp-content\/themes\/enfold-child\/components\/js\/isValid.js\"><\/script>\n\t\t\t\t\t\t\t\t\t\t\t<script>\n\t\t\t\t\t\t\t\t\t\t\t  var input = document.querySelector(\"#phone_number\");\n\t\t\t\t\t\t\t\t\t\t\t  window.intlTelInput(input);\n\t\t\t\t\t\t\t\t\t\t\t<\/script>\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"linkurl\" id=\"linkurl\" value=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2024\/06\/CH0877-Roseg-glacier-panorama.pdf\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"language\" id=\"language\" value=\"Englisch\" \/>\t\t\n\t\t\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"password\" id=\"password\" value=\"56137\" \/>\t\n\t\t\t\t\t\t\t\t\t\t\t<input type=\"submit\" id=\"submit_btn_code\" value=\"Get verification code\" \/>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div id=\"contact_results\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div><div class=\"form-style\" id=\"code_form\">\t\n\t\t\t\t\t\t\t\t\t\t<div id=\"code_body\">\n\t\t\t\t\t\t\t\t\t\t\t<input type=\"text\" name=\"verificationcode\" id=\"verificationcode\" required=\"true\" class=\"input-field\" placeholder=\"Code*\" value=\"\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<input type=\"submit\" id=\"submit_btn\" value=\"Download\" \/><\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div id=\"code_results\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":97866,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"portfolio_entries":[129,134,384],"class_list":["post-95433","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-magic-world-for-rent-switzerland-en","portfolio_entries-pontresina-en-rent","portfolio_entries-rented-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Roseg Glacier Panorama | Pontresina | Engadine | CH0877 - Maurawasescha<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roseg Glacier Panorama | Pontresina | Engadine | CH0877 - Maurawasescha\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/\" \/>\n<meta property=\"og:site_name\" content=\"Maurawasescha\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/maurawasescha\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-05T16:42:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/\",\"url\":\"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/\",\"name\":\"Roseg Glacier Panorama | Pontresina | Engadine | CH0877 - Maurawasescha\",\"isPartOf\":{\"@id\":\"https:\/\/www.maurawasescha.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031.jpg\",\"datePublished\":\"2021-10-07T10:06:03+00:00\",\"dateModified\":\"2026-01-05T16:42:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/#primaryimage\",\"url\":\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031.jpg\",\"contentUrl\":\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031.jpg\",\"width\":1024,\"height\":709},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.maurawasescha.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roseg Glacier Panorama | Pontresina | Engadine | CH0877\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.maurawasescha.com\/en\/#website\",\"url\":\"https:\/\/www.maurawasescha.com\/en\/\",\"name\":\"Maurawasescha\",\"description\":\"Luxury Properties for Rent and Sale\",\"publisher\":{\"@id\":\"https:\/\/www.maurawasescha.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.maurawasescha.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.maurawasescha.com\/en\/#organization\",\"name\":\"Maura Wasescha AG\",\"url\":\"https:\/\/www.maurawasescha.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.maurawasescha.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2015\/05\/maura_wasescha.png\",\"contentUrl\":\"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2015\/05\/maura_wasescha.png\",\"width\":578,\"height\":258,\"caption\":\"Maura Wasescha AG\"},\"image\":{\"@id\":\"https:\/\/www.maurawasescha.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/maurawasescha\/\",\"https:\/\/www.instagram.com\/maurawasescha_agency\/?hl=de\",\"https:\/\/ch.linkedin.com\/in\/maura-wasescha-60bb20104\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Roseg Glacier Panorama | Pontresina | Engadine | CH0877 - Maurawasescha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/","og_locale":"en_US","og_type":"article","og_title":"Roseg Glacier Panorama | Pontresina | Engadine | CH0877 - Maurawasescha","og_url":"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/","og_site_name":"Maurawasescha","article_publisher":"https:\/\/www.facebook.com\/maurawasescha\/","article_modified_time":"2026-01-05T16:42:56+00:00","og_image":[{"width":1024,"height":709,"url":"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/","url":"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/","name":"Roseg Glacier Panorama | Pontresina | Engadine | CH0877 - Maurawasescha","isPartOf":{"@id":"https:\/\/www.maurawasescha.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/#primaryimage"},"image":{"@id":"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/#primaryimage"},"thumbnailUrl":"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031.jpg","datePublished":"2021-10-07T10:06:03+00:00","dateModified":"2026-01-05T16:42:56+00:00","breadcrumb":{"@id":"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/#primaryimage","url":"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031.jpg","contentUrl":"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2021\/12\/Wasescha_APT9_21_031.jpg","width":1024,"height":709},{"@type":"BreadcrumbList","@id":"https:\/\/www.maurawasescha.com\/en\/mw\/park-residence-pontresina-engadin-ch0877\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.maurawasescha.com\/en\/"},{"@type":"ListItem","position":2,"name":"Roseg Glacier Panorama | Pontresina | Engadine | CH0877"}]},{"@type":"WebSite","@id":"https:\/\/www.maurawasescha.com\/en\/#website","url":"https:\/\/www.maurawasescha.com\/en\/","name":"Maurawasescha","description":"Luxury Properties for Rent and Sale","publisher":{"@id":"https:\/\/www.maurawasescha.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.maurawasescha.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.maurawasescha.com\/en\/#organization","name":"Maura Wasescha AG","url":"https:\/\/www.maurawasescha.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.maurawasescha.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2015\/05\/maura_wasescha.png","contentUrl":"https:\/\/www.maurawasescha.com\/wp-content\/uploads\/2015\/05\/maura_wasescha.png","width":578,"height":258,"caption":"Maura Wasescha AG"},"image":{"@id":"https:\/\/www.maurawasescha.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/maurawasescha\/","https:\/\/www.instagram.com\/maurawasescha_agency\/?hl=de","https:\/\/ch.linkedin.com\/in\/maura-wasescha-60bb20104"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.maurawasescha.com\/en\/wp-json\/wp\/v2\/portfolio\/95433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.maurawasescha.com\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.maurawasescha.com\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.maurawasescha.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.maurawasescha.com\/en\/wp-json\/wp\/v2\/comments?post=95433"}],"version-history":[{"count":0,"href":"https:\/\/www.maurawasescha.com\/en\/wp-json\/wp\/v2\/portfolio\/95433\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.maurawasescha.com\/en\/wp-json\/wp\/v2\/media\/97866"}],"wp:attachment":[{"href":"https:\/\/www.maurawasescha.com\/en\/wp-json\/wp\/v2\/media?parent=95433"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.maurawasescha.com\/en\/wp-json\/wp\/v2\/tags?post=95433"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/www.maurawasescha.com\/en\/wp-json\/wp\/v2\/portfolio_entries?post=95433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}